{"id":5721209,"date":"2021-03-09T07:00:00","date_gmt":"2021-03-09T05:00:00","guid":{"rendered":"https:\/\/www.hackrea.net\/?p=5721209"},"modified":"2021-03-09T07:26:57","modified_gmt":"2021-03-09T05:26:57","slug":"carrelage-pastel","status":"publish","type":"post","link":"https:\/\/www.hackrea.net\/fr\/stories\/carrelage-pastel\/","title":{"rendered":"Carrelage pastel: caract\u00e9ristiques d&#8217;utilisation \u00e0 l&#8217;int\u00e9rieur"},"content":{"rendered":"<p>Le monde, plong\u00e9 dans la palette de couleurs de l&#8217;automne, prend une atmosph\u00e8re plus nostalgique. Les flammes chaudes qui dansent dans la chemin\u00e9e vous plongent dans les souvenirs du printemps et de l&#8217;\u00e9t\u00e9 associ\u00e9s aux pastels: la fra\u00eecheur des p\u00eaches, le parfum des fleurs, ou le go\u00fbt de la glace. Cette l\u00e9g\u00e8ret\u00e9 et ce charme des mois d&#8217;\u00e9t\u00e9 peuvent \u00eatre pr\u00e9serv\u00e9s plus longtemps en ajoutant du carrelage des nuances d\u00e9licates \u00e0 l&#8217;int\u00e9rieur, vous permettant de vivre une joie insouciante, quelle que soit la temp\u00e9rature \u00e0 l&#8217;ext\u00e9rieur de la fen\u00eatre.<\/p>\n\n\n\n<p>Les pastels \u00e9taient auparavant utilis\u00e9s principalement pour la chambre d\u2019enfants pour cr\u00e9er une aura idyllique. Ce ton est \u00e9galement souvent retrouv\u00e9 dans l&#8217;atmosph\u00e8re romantique du style proven\u00e7al ou dans les motifs qui pr\u00e9valent dans les cuisines anglaises. Le style de l&#8217;industrialisme moderne a remplac\u00e9 le pastel de la palette de couleurs int\u00e9rieures. Cependant, il reste dans le cercle des propositions populaires et continue de conqu\u00e9rir le monde du design. Les nuances de caf\u00e9 au lait et des tons roses p\u00e2les sont \u00e9galement tendance, d&#8217;autant plus que les jours plus froids arrivent.<\/p>\n\n\n\n<h2 id=\"variete-de-palette-de-couleurs\"  class=\"wp-block-heading\">Vari\u00e9t\u00e9 de palette de couleurs<\/h2>\n\n\n\n<p>Le carrelage beige est une couleur s\u00fbre et neutre. Il n&#8217;y a pas de teinte plus polyvalente qui soit aussi belle avec des couleurs chaudes et froides. Ce ton calme favorise la s\u00e9r\u00e9nit\u00e9, \u00e9voque des \u00e9motions positives, garantit la fra\u00eecheur et, comme le blanc, peut augmenter optiquement l\u2019espace. Il est associ\u00e9 \u00e0 la relaxation, c&#8217;est pourquoi il est souvent utilis\u00e9 dans le salon ou la chambre \u00e0 coucher. Ce ton est associ\u00e9 \u00e0 la l\u00e9g\u00e8ret\u00e9 et au printemps, vous permet de cr\u00e9er un environnement sensuel et se combine de mani\u00e8re optimale avec les tendances modernes.<\/p>\n\n\n\n<p>Certaines personnes se sentent d\u00e9tendues lorsqu&#8217;elles voient du beige \u00e0 l&#8217;int\u00e9rieur, tandis que d&#8217;autres, au contraire, le consid\u00e8rent comme un signe d&#8217;ennui et de manque de cr\u00e9ativit\u00e9. Pour \u00e9viter le sentiment de monotonie et obtenir en m\u00eame temps un design holistique, il convient de combiner le carrelage beige classique avec du gris ou du blanc, d\u00e9cor\u00e9 avec des accents noirs. Les rainures diagonales caract\u00e9ristiques et la texture rugueuse des carreaux donnent \u00e0 l&#8217;int\u00e9rieur un aspect moderne, tandis que le motif en bois chaleureux des carreaux de sol ajoute de l&#8217;int\u00e9grit\u00e9.<\/p>\n\n\n\n<p>Le carrelage beige est \u00e9galement une alternative au blanc, souvent utilis\u00e9 pour att\u00e9nuer les couleurs vives et \u00e9clairer les petits int\u00e9rieurs. Les propri\u00e9t\u00e9s optiques du carrelage de couleur cr\u00e8me avec un motif de pierre d\u00e9corative refl\u00e8tent les rayons du soleil sur une texture int\u00e9ressante, cr\u00e9ant une sensation d&#8217;espace. La solution peut \u00eatre utilis\u00e9e en toute s\u00e9curit\u00e9 dans de petits espaces et utiliser en outre des teintes plus fonc\u00e9es, telles que le graphite ou le noir. Le contraste qui en r\u00e9sulte ne submerge pas l&#8217;int\u00e9rieur et les couleurs d\u00e9licates du carrelage rendent l&#8217;atmosph\u00e8re plus chaleureuse et plus harmonieuse. Combiner des tons terreux avec des pastels est une excellente option pour accentuer une ambiance shabby chic, rustique ou vintage. L&#8217;impressionnante surface en pierre est indispensable pour cr\u00e9er une ambiance romantique, f\u00e9minine et sensuelle.<\/p>\n\n\n<style>.uid-74b3514285cfd161  .gt3pg-isotope-item {\n\tpadding-right: 20px;\n\tpadding-bottom: 20px;\n}\n.uid-74b3514285cfd161  .gallery-isotope-wrapper {\n\tmargin-right: -20px;\n\tmargin-bottom: -20px;\n}\n<\/style><div id=\"uid-74b3514285cfd161\" data-gt3pg-block=\"grid\" data-index=\"1\" class=\"gt3-photo-gallery-pro--isotope_gallery uid-74b3514285cfd161 gt3pg-pro--wrapper gt3pg-pro--grid\">\t\t<div class=\"hover-default gt3pg-isotope-gallery columns-4 gallery-grid   corner-rounded square\" data-cols=\"4\" data-cols-tablet=\"3\" data-cols-mobile=\"2\">\r\n\t\t\t\t\t\t\t\t\t<div class=\"gallery-isotope-wrapper\">\r\n\t\t\t\t<div class=\"gt3pg-isotope-item loading\" ><div class=\"isotope_item-wrapper\"><a href=\"https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-tiles-1-768x905.jpg\" class=\"gt3pg-lightbox\"  target=\"_blank\" data-elementor-open-lightbox=\"no\"><div class=\"img-wrapper\"><img fetchpriority=\"high\" decoding=\"async\" width=\"768\" height=\"905\" src=\"https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-tiles-1-768x905.jpg\" class=\"skip-lazy\" alt=\"\" loading=\"eager\" data-lazy-srcset=\"https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-tiles-1-768x905.jpg 768w,  https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-tiles-1-255x300.jpg 255w,  https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-tiles-1-600x707.jpg 600w\" data-lazy-sizes=\"(max-width: 768px) 100vw, 768px\" data-lazy-src=\"https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-tiles-1-768x905.jpg?is-pending-load=1\" srcset=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAAFoAAABpCAYAAAC6RjQBAAAACXBIWXMAAA7EAAAOxAGVKw4bAAAAO0lEQVR42u3BAQEAAACCIP+vbkhAAQAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAwJEBlBEAAUNt7o4AAAAASUVORK5CYII=\" \/><\/div><\/a><\/div><a href=\"https:\/\/www.pinterest.com\/pin\/create\/button\/\" data-pin-do=\"buttonPin\" data-pin-hover=\"true\" data-pin-media=\"https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-tiles-1-768x905.jpg\" data-pin-url=\"\" style=\"position: absolute; top: 10px; left:10px;\"> <\/a><\/div><div class=\"gt3pg-isotope-item loading\" ><div class=\"isotope_item-wrapper\"><a href=\"https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-tiles-2-768x559.jpg\" class=\"gt3pg-lightbox\"  target=\"_blank\" data-elementor-open-lightbox=\"no\"><div class=\"img-wrapper\"><img decoding=\"async\" width=\"768\" height=\"559\" src=\"https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-tiles-2-768x559.jpg\" class=\"skip-lazy\" alt=\"\" loading=\"eager\" data-lazy-srcset=\"https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-tiles-2-768x559.jpg 768w,  https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-tiles-2-300x218.jpg 300w,  https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-tiles-2-600x437.jpg 600w\" data-lazy-sizes=\"(max-width: 768px) 100vw, 768px\" data-lazy-src=\"https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-tiles-2-768x559.jpg?is-pending-load=1\" srcset=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAAIsAAABlCAYAAAB9VxANAAAACXBIWXMAAA7EAAAOxAGVKw4bAAAATUlEQVR42u3BMQEAAADCoPVP7WsIoAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAOAM28EAAesXru4AAAAASUVORK5CYII=\" \/><\/div><\/a><\/div><a href=\"https:\/\/www.pinterest.com\/pin\/create\/button\/\" data-pin-do=\"buttonPin\" data-pin-hover=\"true\" data-pin-media=\"https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-tiles-2-768x559.jpg\" data-pin-url=\"\" style=\"position: absolute; top: 10px; left:10px;\"> <\/a><\/div><div class=\"gt3pg-isotope-item loading\" ><div class=\"isotope_item-wrapper\"><a href=\"https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-tiles-3-768x677.jpg\" class=\"gt3pg-lightbox\"  target=\"_blank\" data-elementor-open-lightbox=\"no\"><div class=\"img-wrapper\"><img decoding=\"async\" width=\"768\" height=\"677\" src=\"https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-tiles-3-768x677.jpg\" class=\"skip-lazy\" alt=\"\" loading=\"eager\" data-lazy-srcset=\"https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-tiles-3-768x677.jpg 768w,  https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-tiles-3-300x265.jpg 300w,  https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-tiles-3-600x529.jpg 600w\" data-lazy-sizes=\"(max-width: 768px) 100vw, 768px\" data-lazy-src=\"https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-tiles-3-768x677.jpg?is-pending-load=1\" srcset=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAAGYAAABaCAYAAABKZyO0AAAACXBIWXMAAA7EAAAOxAGVKw4bAAAAO0lEQVR42u3BAQ0AAADCoPdPbQ43oAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAA4MkAj8oAAY4NbXEAAAAASUVORK5CYII=\" \/><\/div><\/a><\/div><a href=\"https:\/\/www.pinterest.com\/pin\/create\/button\/\" data-pin-do=\"buttonPin\" data-pin-hover=\"true\" data-pin-media=\"https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-tiles-3-768x677.jpg\" data-pin-url=\"\" style=\"position: absolute; top: 10px; left:10px;\"> <\/a><\/div><div class=\"gt3pg-isotope-item loading\" ><div class=\"isotope_item-wrapper\"><a href=\"https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-tiles-4-768x464.jpg\" class=\"gt3pg-lightbox\"  target=\"_blank\" data-elementor-open-lightbox=\"no\"><div class=\"img-wrapper\"><img decoding=\"async\" width=\"768\" height=\"464\" src=\"https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-tiles-4-768x464.jpg\" class=\"skip-lazy\" alt=\"\" loading=\"eager\" data-lazy-srcset=\"https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-tiles-4-768x464.jpg 768w,  https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-tiles-4-300x181.jpg 300w,  https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-tiles-4-600x363.jpg 600w\" data-lazy-sizes=\"(max-width: 768px) 100vw, 768px\" data-lazy-src=\"https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-tiles-4-768x464.jpg?is-pending-load=1\" srcset=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAAMgAAAB5CAYAAAB8zm5OAAAACXBIWXMAAA7EAAAOxAGVKw4bAAAAdUlEQVR42u3BAQ0AAADCoPdPbQ43oAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAIAbA3qoAAEEVTtWAAAAAElFTkSuQmCC\" \/><\/div><\/a><\/div><a href=\"https:\/\/www.pinterest.com\/pin\/create\/button\/\" data-pin-do=\"buttonPin\" data-pin-hover=\"true\" data-pin-media=\"https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-tiles-4-768x464.jpg\" data-pin-url=\"\" style=\"position: absolute; top: 10px; left:10px;\"> <\/a><\/div>\t\t\t<\/div>\r\n\t\t\t<div class=\"gallery-preloader\"><svg width=\"50\" height=\"50\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 100 100\" preserveAspectRatio=\"xMidYMid\" class=\"lds-eclipse\"><path stroke=\"none\" d=\"M10 50A40 40 0 0 0 90 50A40 42 0 0 1 10 50\"><\/path><\/svg><\/div>\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t<script type=\"application\/json\" id=\"settings--uid-74b3514285cfd161\">{\"id\":1,\"uid\":\"uid-74b3514285cfd161\",\"grid_type\":\"square\",\"lazyLoad\":true,\"isotopeOptions\":{\"stagger\":0},\"lightbox\":{\"enable\":true,\"options\":{\"showTitle\":false,\"showCaption\":false,\"descriptionProperty\":\"caption\",\"allowDownload\":false,\"allowZoom\":true,\"socials\":true,\"deepLink\":false,\"stretchImages\":false,\"thumbnailIndicators\":true,\"startSlideshow\":false,\"slideshowInterval\":6000,\"instance\":1,\"customClass\":\"style-dark\",\"rightClick\":false,\"externalPosters\":false,\"ytWidth\":false,\"toggleControlsOnSlideClick\":false,\"closeOnSlideClick\":false,\"videoAutoplay\":false,\"animationType\":\"slide\",\"simpleStyle\":false,\"continuous\":true}},\"items\":[{\"href\":\"https:\\\/\\\/www.hackrea.net\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/Pastel-tiles-1.jpg\",\"title\":\"Pastel tiles-1\",\"caption\":\"\",\"description\":\"\",\"alt\":\"\",\"thumbnail\":\"https:\\\/\\\/www.hackrea.net\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/Pastel-tiles-1-150x150.jpg\",\"is_video\":0,\"image_id\":5719527,\"width\":900,\"height\":1060,\"item_class_list\":[],\"external_link\":\"\",\"local_index\":0},{\"href\":\"https:\\\/\\\/www.hackrea.net\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/Pastel-tiles-2.jpg\",\"title\":\"Pastel tiles-2\",\"caption\":\"\",\"description\":\"\",\"alt\":\"\",\"thumbnail\":\"https:\\\/\\\/www.hackrea.net\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/Pastel-tiles-2-150x150.jpg\",\"is_video\":0,\"image_id\":5719528,\"width\":1390,\"height\":1012,\"item_class_list\":[],\"external_link\":\"\",\"local_index\":1},{\"href\":\"https:\\\/\\\/www.hackrea.net\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/Pastel-tiles-3.jpg\",\"title\":\"Pastel tiles-3\",\"caption\":\"\",\"description\":\"\",\"alt\":\"\",\"thumbnail\":\"https:\\\/\\\/www.hackrea.net\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/Pastel-tiles-3-150x150.jpg\",\"is_video\":0,\"image_id\":5719529,\"width\":1024,\"height\":903,\"item_class_list\":[],\"external_link\":\"\",\"local_index\":2},{\"href\":\"https:\\\/\\\/www.hackrea.net\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/Pastel-tiles-4.jpg\",\"title\":\"Pastel tiles-4\",\"caption\":\"\",\"description\":\"\",\"alt\":\"\",\"thumbnail\":\"https:\\\/\\\/www.hackrea.net\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/Pastel-tiles-4-150x150.jpg\",\"is_video\":0,\"image_id\":5719530,\"width\":2000,\"height\":1209,\"item_class_list\":[],\"external_link\":\"\",\"local_index\":3}],\"modules\":[\"Lightbox\"]}<\/script><\/div>\n\n\n<h2 id=\"pastel-et-brique-rouge\"  class=\"wp-block-heading\">Pastel et brique rouge<\/h2>\n\n\n\n<p>L&#8217;utilisation du brique rouge est une tendance \u00e0 la mode pour revitaliser les int\u00e9rieurs dans des tons beiges. Le th\u00e8me est le plus souvent associ\u00e9 \u00e0 une ambiance industrielle mais peut \u00e9galement \u00eatre utilis\u00e9 dans un d\u00e9cor scandinave ou classique. Le carrelage de couleurs neutres combin\u00e9 \u00e0 un mat\u00e9riau textur\u00e9 avec effet brique forme un \u00e9quilibre entre le caract\u00e8re original de l&#8217;int\u00e9rieur et l&#8217;atmosph\u00e8re de d\u00e9tente. Cependant, il faut se rappeler que de grandes surfaces, d\u00e9cor\u00e9es de brique, surchargent la pi\u00e8ce. Par cons\u00e9quent, il est pr\u00e9f\u00e9rable d&#8217;utiliser cette solution sur un fragment sp\u00e9cifique, tel qu&#8217;un mur de t\u00e9l\u00e9vision ou une zone adjacente \u00e0 une fen\u00eatre. La combinaison de briques et de carreaux beiges est en parfaite harmonie avec le parquet.<\/p>\n\n\n\n<h2 id=\"beton-et-pastel\"  class=\"wp-block-heading\">B\u00e9ton et pastel<\/h2>\n\n\n\n<p>La plupart des appartements \u00e9tant domin\u00e9s par le style industriel et loft, le b\u00e9ton architectural est devenu la d\u00e9coration principale de l&#8217;int\u00e9rieur. Habituellement, il est accompagn\u00e9 de tons allant du graphite \u00e0 de subtiles nuances de gris, compl\u00e9t\u00e9s par des \u00e9l\u00e9ments expressifs de blanc et de noir. Ensemble, ils cr\u00e9ent une image minimaliste originale, dans laquelle il n&#8217;y a pas de d\u00e9tails inutiles. Lors de la d\u00e9coration d&#8217;une pi\u00e8ce, la puissance des pastels diversifie la teinte grise solide des dalles rugueuses de grand format. De d\u00e9licates nuances de rose poudr\u00e9 ou de bruy\u00e8re, utilis\u00e9es comme tissus et textures doux, compl\u00e8tent l&#8217;ensemble carrel\u00e9, apportant fra\u00eecheur et l\u00e9g\u00e8ret\u00e9 \u00e0 la pi\u00e8ce sans perdre l&#8217;ambiance moderne.<\/p>\n\n\n\n<h2 id=\"pastel-avec-accents-expressifs\"  class=\"wp-block-heading\">Pastel avec accents expressifs<\/h2>\n\n\n\n<p>La combinaison de couleurs pastel utilis\u00e9es sur les sols, les murs, les meubles ou les d\u00e9corations garantit un d\u00e9cor avec une touche romantique. Les possibilit\u00e9s stylistiques du ton ne s&#8217;arr\u00eatent pas l\u00e0, car son caract\u00e8re neutre est soutenu par une combinaison de couleurs intenses et sombres, ce qui permet une composition audacieuse et efficace. La combinaison \u00e9l\u00e9gante de carrelage rose et noir donne de la profondeur \u00e0 l&#8217;int\u00e9rieur et, associ\u00e9e \u00e0 des accessoires dans un ton similaire, cr\u00e9e une atmosph\u00e8re typiquement moderne. Ce merveilleux accent ne convient pas seulement aux int\u00e9rieurs au caract\u00e8re moderne &#8211; mais il constitue \u00e9galement un excellent ajout au d\u00e9cor vintage ou scandinave.<\/p>\n\n\n\n<p>Le carrelage noir effet brique n\u2019est pas la fin d&#8217;id\u00e9es extraordinaires pour l&#8217;incarnation d&#8217;un paysage fabuleux avec des pastels en t\u00eate r\u00f4le. Parfois, avec quelques d\u00e9tails nets, vous pouvez briser l&#8217;ambiance tamis\u00e9e d&#8217;un int\u00e9rieur et obtenir des r\u00e9sultats \u00e9tonnants. Ce ne sont pas seulement des feuilles de plantes succulentes, des oreillers et des couvertures en tissu doux ou un grand miroir rond qui animent la pi\u00e8ce. En plus d&#8217;eux, le carrelage au design vintage semble int\u00e9ressant sur le mur. Pour vous faire une id\u00e9e de l&#8217;ambiance estivale, utilisez des parquets \u00e0 motif bois et compl\u00e9tez le d\u00e9cor avec des accessoires en m\u00e9tal design qui sont \u00e0 la mode depuis plusieurs ann\u00e9es.<\/p>\n\n\n\n<h2 id=\"pastels-dans-toute-la-maison\"  class=\"wp-block-heading\">Pastels dans toute la maison<\/h2>\n\n\n\n<p>L&#8217;amour pour les pastels ne se limite pas \u00e0 l&#8217;espace de vie, car les nuances claires ont longtemps \u00e9t\u00e9 un chef de file dans la cr\u00e9ation de l&#8217;environnement d&#8217;une maison. La d\u00e9licate couleur beige r\u00e8gne sur les fa\u00e7ades des b\u00e2timents classiques et modernes et cr\u00e9e \u00e9galement un ensemble esth\u00e9tique avec des carreaux de graphite, noirs ou rouges qui correspondent parfaitement au paysage verdoyant qui l&#8217;entoure. Pour diversifier la forme ou mettre en valeur certains \u00e9l\u00e9ments architecturaux, comme une terrasse ou une entr\u00e9e, il convient d&#8217;utiliser le potentiel du carrelage inspir\u00e9 de la pierre naturelle. La texture vari\u00e9e du carreau avec des rayures et des rainures visibles ressemble \u00e0 des plages de sable pour un effet l\u00e9ger et harmonieux. En plus des qualit\u00e9s visuelles, ce carrelage est un rev\u00eatement pratique et abordable. Il facilite l&#8217;installation et est durable en fonctionnement, vous permettant de pr\u00e9server l&#8217;apparence d&#8217;origine de la fa\u00e7ade de la maison en plein soleil en \u00e9t\u00e9 et en hiver.<\/p>\n\n\n\n<h2 id=\"carrelage-couleur-pastel-conclusions-galerie-de-photos\"  class=\"wp-block-heading\">Carrelage couleur pastel: Conclusions + Galerie de photos<\/h2>\n\n\n\n<p>Le pastel est une sorte de compensation pour le manque de soleil et les jours nuageux \u00e0 l&#8217;int\u00e9rieur, qui deviennent une r\u00e9alit\u00e9 quotidienne \u00e0 l&#8217;automne. Un regain d&#8217;\u00e9nergie positive qui l&#8217;accompagne est une recette efficace pour la l\u00e9thargie, la d\u00e9pression de novembre et l&#8217;envie d&#8217;\u00e9t\u00e9. Cette palette de couleurs d\u00e9licate convient aux styles scandinaves et industriels. Le pastel aime la compagnie des carreaux blancs et noirs ou des briques rouges.<\/p>\n\n\n<style>.uid-04c18ee4456309d3  .gt3pg-isotope-item {\n\tpadding-right: 20px;\n\tpadding-bottom: 20px;\n}\n.uid-04c18ee4456309d3  .gallery-isotope-wrapper {\n\tmargin-right: -20px;\n\tmargin-bottom: -20px;\n}\n<\/style><div id=\"uid-04c18ee4456309d3\" data-gt3pg-block=\"grid\" data-index=\"2\" class=\"gt3-photo-gallery-pro--isotope_gallery uid-04c18ee4456309d3 gt3pg-pro--wrapper gt3pg-pro--grid\">\t\t<div class=\"hover-default gt3pg-isotope-gallery columns-3 gallery-grid   corner-rounded square\" data-cols=\"3\" data-cols-tablet=\"3\" data-cols-mobile=\"2\">\r\n\t\t\t\t\t\t\t\t\t<div class=\"gallery-isotope-wrapper\">\r\n\t\t\t\t<div class=\"gt3pg-isotope-item loading\" ><div class=\"isotope_item-wrapper\"><a href=\"https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/beige-combined-with-other-colors-1-768x768.jpg\" class=\"gt3pg-lightbox\"  target=\"_blank\" data-elementor-open-lightbox=\"no\"><div class=\"img-wrapper\"><img decoding=\"async\" width=\"768\" height=\"768\" src=\"https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/beige-combined-with-other-colors-1-768x768.jpg\" class=\"skip-lazy\" alt=\"\" loading=\"eager\" data-lazy-srcset=\"https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/beige-combined-with-other-colors-1-768x768.jpg 768w,  https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/beige-combined-with-other-colors-1-300x300.jpg 300w,  https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/beige-combined-with-other-colors-1-150x150.jpg 150w,  https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/beige-combined-with-other-colors-1-200x200.jpg 200w,  https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/beige-combined-with-other-colors-1-600x600.jpg 600w,  https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/beige-combined-with-other-colors-1-100x100.jpg 100w\" data-lazy-sizes=\"(max-width: 768px) 100vw, 768px\" data-lazy-src=\"https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/beige-combined-with-other-colors-1-768x768.jpg?is-pending-load=1\" srcset=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAAFIAAABSCAYAAADHLIObAAAACXBIWXMAAA7EAAAOxAGVKw4bAAAAMUlEQVR42u3BMQEAAADCoPVPbQ0PoAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAA3gxpYgABEqsjVQAAAABJRU5ErkJggg==\" \/><\/div><\/a><\/div><a href=\"https:\/\/www.pinterest.com\/pin\/create\/button\/\" data-pin-do=\"buttonPin\" data-pin-hover=\"true\" data-pin-media=\"https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/beige-combined-with-other-colors-1-768x768.jpg\" data-pin-url=\"\" style=\"position: absolute; top: 10px; left:10px;\"> <\/a><\/div><div class=\"gt3pg-isotope-item loading\" ><div class=\"isotope_item-wrapper\"><a href=\"https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/beige-combined-with-other-colors-2-768x768.jpg\" class=\"gt3pg-lightbox\"  target=\"_blank\" data-elementor-open-lightbox=\"no\"><div class=\"img-wrapper\"><img decoding=\"async\" width=\"768\" height=\"768\" src=\"https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/beige-combined-with-other-colors-2-768x768.jpg\" class=\"skip-lazy\" alt=\"\" loading=\"eager\" data-lazy-srcset=\"https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/beige-combined-with-other-colors-2-768x768.jpg 768w,  https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/beige-combined-with-other-colors-2-300x300.jpg 300w,  https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/beige-combined-with-other-colors-2-150x150.jpg 150w,  https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/beige-combined-with-other-colors-2-200x200.jpg 200w,  https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/beige-combined-with-other-colors-2-600x600.jpg 600w,  https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/beige-combined-with-other-colors-2-100x100.jpg 100w\" data-lazy-sizes=\"(max-width: 768px) 100vw, 768px\" data-lazy-src=\"https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/beige-combined-with-other-colors-2-768x768.jpg?is-pending-load=1\" srcset=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAAFAAAABQCAYAAACOEfKtAAAACXBIWXMAAA7EAAAOxAGVKw4bAAAAMElEQVR42u3BMQEAAADCoPVPbQ0PoAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAIAXA2RQAAEB5C4HAAAAAElFTkSuQmCC\" \/><\/div><\/a><\/div><a href=\"https:\/\/www.pinterest.com\/pin\/create\/button\/\" data-pin-do=\"buttonPin\" data-pin-hover=\"true\" data-pin-media=\"https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/beige-combined-with-other-colors-2-768x768.jpg\" data-pin-url=\"\" style=\"position: absolute; top: 10px; left:10px;\"> <\/a><\/div><div class=\"gt3pg-isotope-item loading\" ><div class=\"isotope_item-wrapper\"><a href=\"https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/beige-combined-with-other-colors-3-768x768.jpg\" class=\"gt3pg-lightbox\"  target=\"_blank\" data-elementor-open-lightbox=\"no\"><div class=\"img-wrapper\"><img decoding=\"async\" width=\"768\" height=\"768\" src=\"https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/beige-combined-with-other-colors-3-768x768.jpg\" class=\"skip-lazy\" alt=\"\" loading=\"eager\" data-lazy-srcset=\"https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/beige-combined-with-other-colors-3-768x768.jpg 768w,  https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/beige-combined-with-other-colors-3-300x300.jpg 300w,  https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/beige-combined-with-other-colors-3-150x150.jpg 150w,  https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/beige-combined-with-other-colors-3-200x200.jpg 200w,  https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/beige-combined-with-other-colors-3-600x600.jpg 600w,  https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/beige-combined-with-other-colors-3-100x100.jpg 100w\" data-lazy-sizes=\"(max-width: 768px) 100vw, 768px\" data-lazy-src=\"https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/beige-combined-with-other-colors-3-768x768.jpg?is-pending-load=1\" srcset=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAAGQAAABkCAYAAABw4pVUAAAACXBIWXMAAA7EAAAOxAGVKw4bAAAAPklEQVR42u3BMQEAAADCoPVPbQsvoAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAgKcBnKQAAdh7HF4AAAAASUVORK5CYII=\" \/><\/div><\/a><\/div><a href=\"https:\/\/www.pinterest.com\/pin\/create\/button\/\" data-pin-do=\"buttonPin\" data-pin-hover=\"true\" data-pin-media=\"https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/beige-combined-with-other-colors-3-768x768.jpg\" data-pin-url=\"\" style=\"position: absolute; top: 10px; left:10px;\"> <\/a><\/div>\t\t\t<\/div>\r\n\t\t\t<div class=\"gallery-preloader\"><svg width=\"50\" height=\"50\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 100 100\" preserveAspectRatio=\"xMidYMid\" class=\"lds-eclipse\"><path stroke=\"none\" d=\"M10 50A40 40 0 0 0 90 50A40 42 0 0 1 10 50\"><\/path><\/svg><\/div>\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t<script type=\"application\/json\" id=\"settings--uid-04c18ee4456309d3\">{\"id\":1,\"uid\":\"uid-04c18ee4456309d3\",\"grid_type\":\"square\",\"lazyLoad\":true,\"isotopeOptions\":{\"stagger\":0},\"lightbox\":{\"enable\":true,\"options\":{\"showTitle\":false,\"showCaption\":false,\"descriptionProperty\":\"caption\",\"allowDownload\":false,\"allowZoom\":true,\"socials\":true,\"deepLink\":false,\"stretchImages\":false,\"thumbnailIndicators\":true,\"startSlideshow\":false,\"slideshowInterval\":6000,\"instance\":2,\"customClass\":\"style-dark\",\"rightClick\":false,\"externalPosters\":false,\"ytWidth\":false,\"toggleControlsOnSlideClick\":false,\"closeOnSlideClick\":false,\"videoAutoplay\":false,\"animationType\":\"slide\",\"simpleStyle\":false,\"continuous\":true}},\"items\":[{\"href\":\"https:\\\/\\\/www.hackrea.net\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/beige-combined-with-other-colors-1.jpg\",\"title\":\"beige combined with other colors-1\",\"caption\":\"\",\"description\":\"\",\"alt\":\"\",\"thumbnail\":\"https:\\\/\\\/www.hackrea.net\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/beige-combined-with-other-colors-1-150x150.jpg\",\"is_video\":0,\"image_id\":5719531,\"width\":819,\"height\":819,\"item_class_list\":[],\"external_link\":\"\",\"local_index\":0},{\"href\":\"https:\\\/\\\/www.hackrea.net\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/beige-combined-with-other-colors-2.jpg\",\"title\":\"beige combined with other colors-2\",\"caption\":\"\",\"description\":\"\",\"alt\":\"\",\"thumbnail\":\"https:\\\/\\\/www.hackrea.net\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/beige-combined-with-other-colors-2-150x150.jpg\",\"is_video\":0,\"image_id\":5719532,\"width\":800,\"height\":800,\"item_class_list\":[],\"external_link\":\"\",\"local_index\":1},{\"href\":\"https:\\\/\\\/www.hackrea.net\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/beige-combined-with-other-colors-3.jpg\",\"title\":\"beige combined with other colors-3\",\"caption\":\"\",\"description\":\"\",\"alt\":\"\",\"thumbnail\":\"https:\\\/\\\/www.hackrea.net\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/beige-combined-with-other-colors-3-150x150.jpg\",\"is_video\":0,\"image_id\":5719533,\"width\":1002,\"height\":1002,\"item_class_list\":[],\"external_link\":\"\",\"local_index\":2}],\"modules\":[\"Lightbox\"]}<\/script><\/div>\n\n\n<h2 id=\"pastel-colored-tiles-conclusions-photo-gallery\"  class=\"wp-block-heading\">Pastel-colored tiles: Conclusions + Photo Gallery<\/h2>\n\n\n\n<p>Pastel is a kind of compensation for the lack of sun and cloudy days in the interior, which become an everyday reality in autumn. An accompanying boost of positive energy is an effective recipe for lethargy, November depression, and yearning for summer. This delicate color scheme looks good in both Scandinavian and industrial styles. Pastel likes the company of white and black tiles or red bricks.<\/p>\n\n\n<style>.uid-a1962ff3b47b5dfd  .gt3pg-isotope-item {\n\tpadding-right: 20px;\n\tpadding-bottom: 20px;\n}\n.uid-a1962ff3b47b5dfd  .gallery-isotope-wrapper {\n\tmargin-right: -20px;\n\tmargin-bottom: -20px;\n}\n<\/style><div id=\"uid-a1962ff3b47b5dfd\" data-gt3pg-block=\"grid\" data-index=\"3\" class=\"gt3-photo-gallery-pro--isotope_gallery uid-a1962ff3b47b5dfd gt3pg-pro--wrapper gt3pg-pro--grid\">\t\t<div class=\"hover-default gt3pg-isotope-gallery columns-3 gallery-grid   corner-rounded square\" data-cols=\"3\" data-cols-tablet=\"3\" data-cols-mobile=\"2\">\r\n\t\t\t\t\t\t\t\t\t<div class=\"gallery-isotope-wrapper\">\r\n\t\t\t\t<div class=\"gt3pg-isotope-item loading\" ><div class=\"isotope_item-wrapper\"><a href=\"https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-colored-tiles-1-768x551.jpg\" class=\"gt3pg-lightbox\"  target=\"_blank\" data-elementor-open-lightbox=\"no\"><div class=\"img-wrapper\"><img decoding=\"async\" width=\"768\" height=\"551\" src=\"https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-colored-tiles-1-768x551.jpg\" class=\"skip-lazy\" alt=\"\" loading=\"eager\" data-lazy-srcset=\"https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-colored-tiles-1-768x551.jpg 768w,  https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-colored-tiles-1-300x215.jpg 300w,  https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-colored-tiles-1-600x431.jpg 600w\" data-lazy-sizes=\"(max-width: 768px) 100vw, 768px\" data-lazy-src=\"https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-colored-tiles-1-768x551.jpg?is-pending-load=1\" srcset=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAAFoAAABACAYAAACa5WD\/AAAACXBIWXMAAA7EAAAOxAGVKw4bAAAALUlEQVR42u3BMQEAAADCoPVPbQ0PoAAAAAAAAAAAAAAAAAAAAAAAAAAAAAB4MlpAAAGEdIU8AAAAAElFTkSuQmCC\" \/><\/div><\/a><\/div><a href=\"https:\/\/www.pinterest.com\/pin\/create\/button\/\" data-pin-do=\"buttonPin\" data-pin-hover=\"true\" data-pin-media=\"https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-colored-tiles-1-768x551.jpg\" data-pin-url=\"\" style=\"position: absolute; top: 10px; left:10px;\"> <\/a><\/div><div class=\"gt3pg-isotope-item loading\" ><div class=\"isotope_item-wrapper\"><a href=\"https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-colored-tiles-2-768x516.jpg\" class=\"gt3pg-lightbox\"  target=\"_blank\" data-elementor-open-lightbox=\"no\"><div class=\"img-wrapper\"><img decoding=\"async\" width=\"768\" height=\"516\" src=\"https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-colored-tiles-2-768x516.jpg\" class=\"skip-lazy\" alt=\"\" loading=\"eager\" data-lazy-srcset=\"https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-colored-tiles-2-768x516.jpg 768w,  https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-colored-tiles-2-300x201.jpg 300w,  https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-colored-tiles-2-600x403.jpg 600w\" data-lazy-sizes=\"(max-width: 768px) 100vw, 768px\" data-lazy-src=\"https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-colored-tiles-2-768x516.jpg?is-pending-load=1\" srcset=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAAJUAAABkCAYAAACPbHLzAAAACXBIWXMAAA7EAAAOxAGVKw4bAAAAUUlEQVR42u3BMQEAAADCoPVPbQsvoAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAICHAek0AAGpPtoBAAAAAElFTkSuQmCC\" \/><\/div><\/a><\/div><a href=\"https:\/\/www.pinterest.com\/pin\/create\/button\/\" data-pin-do=\"buttonPin\" data-pin-hover=\"true\" data-pin-media=\"https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-colored-tiles-2-768x516.jpg\" data-pin-url=\"\" style=\"position: absolute; top: 10px; left:10px;\"> <\/a><\/div><div class=\"gt3pg-isotope-item loading\" ><div class=\"isotope_item-wrapper\"><a href=\"https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-colored-tiles-3.jpg\" class=\"gt3pg-lightbox\"  target=\"_blank\" data-elementor-open-lightbox=\"no\"><div class=\"img-wrapper\"><img decoding=\"async\" width=\"735\" height=\"600\" src=\"https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-colored-tiles-3.jpg\" class=\"skip-lazy\" alt=\"\" loading=\"eager\" data-lazy-srcset=\"https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-colored-tiles-3.jpg 735w,  https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-colored-tiles-3-300x245.jpg 300w,  https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-colored-tiles-3-600x490.jpg 600w\" data-lazy-sizes=\"(max-width: 735px) 100vw, 735px\" data-lazy-src=\"https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-colored-tiles-3.jpg?is-pending-load=1\" srcset=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAAEoAAAA8CAYAAADBqyytAAAACXBIWXMAAA7EAAAOxAGVKw4bAAAAKElEQVR42u3BMQEAAADCoPVP7W8GoAAAAAAAAAAAAAAAAAAAAAAAeANFnAAB1gHDxAAAAABJRU5ErkJggg==\" \/><\/div><\/a><\/div><a href=\"https:\/\/www.pinterest.com\/pin\/create\/button\/\" data-pin-do=\"buttonPin\" data-pin-hover=\"true\" data-pin-media=\"https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-colored-tiles-3.jpg\" data-pin-url=\"\" style=\"position: absolute; top: 10px; left:10px;\"> <\/a><\/div><div class=\"gt3pg-isotope-item loading\" ><div class=\"isotope_item-wrapper\"><a href=\"https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-colored-tiles-4-768x516.jpg\" class=\"gt3pg-lightbox\"  target=\"_blank\" data-elementor-open-lightbox=\"no\"><div class=\"img-wrapper\"><img decoding=\"async\" width=\"768\" height=\"516\" src=\"https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-colored-tiles-4-768x516.jpg\" class=\"skip-lazy\" alt=\"\" loading=\"eager\" data-lazy-srcset=\"https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-colored-tiles-4-768x516.jpg 768w,  https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-colored-tiles-4-300x201.jpg 300w,  https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-colored-tiles-4-600x403.jpg 600w\" data-lazy-sizes=\"(max-width: 768px) 100vw, 768px\" data-lazy-src=\"https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-colored-tiles-4-768x516.jpg?is-pending-load=1\" srcset=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAAIUAAABZCAYAAAAQJudoAAAACXBIWXMAAA7EAAAOxAGVKw4bAAAARElEQVR42u3BAQ0AAADCoPdPbQ8HFAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAHBtuU0AAZ97QE0AAAAASUVORK5CYII=\" \/><\/div><\/a><\/div><a href=\"https:\/\/www.pinterest.com\/pin\/create\/button\/\" data-pin-do=\"buttonPin\" data-pin-hover=\"true\" data-pin-media=\"https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-colored-tiles-4-768x516.jpg\" data-pin-url=\"\" style=\"position: absolute; top: 10px; left:10px;\"> <\/a><\/div><div class=\"gt3pg-isotope-item loading\" ><div class=\"isotope_item-wrapper\"><a href=\"https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-colored-tiles-5-768x432.jpg\" class=\"gt3pg-lightbox\"  target=\"_blank\" data-elementor-open-lightbox=\"no\"><div class=\"img-wrapper\"><img decoding=\"async\" width=\"768\" height=\"432\" src=\"https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-colored-tiles-5-768x432.jpg\" class=\"skip-lazy\" alt=\"\" loading=\"eager\" data-lazy-srcset=\"https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-colored-tiles-5-768x432.jpg 768w,  https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-colored-tiles-5-300x169.jpg 300w,  https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-colored-tiles-5-600x338.jpg 600w\" data-lazy-sizes=\"(max-width: 768px) 100vw, 768px\" data-lazy-src=\"https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-colored-tiles-5-768x432.jpg?is-pending-load=1\" srcset=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAAL4AAABqCAYAAAAC2+ukAAAACXBIWXMAAA7EAAAOxAGVKw4bAAAAZUlEQVR42u3BAQ0AAADCoPdPbQ43oAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAF4MOykAAZXvTJwAAAAASUVORK5CYII=\" \/><\/div><\/a><\/div><a href=\"https:\/\/www.pinterest.com\/pin\/create\/button\/\" data-pin-do=\"buttonPin\" data-pin-hover=\"true\" data-pin-media=\"https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-colored-tiles-5-768x432.jpg\" data-pin-url=\"\" style=\"position: absolute; top: 10px; left:10px;\"> <\/a><\/div><div class=\"gt3pg-isotope-item loading\" ><div class=\"isotope_item-wrapper\"><a href=\"https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-colored-tiles-6-768x576.jpg\" class=\"gt3pg-lightbox\"  target=\"_blank\" data-elementor-open-lightbox=\"no\"><div class=\"img-wrapper\"><img decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-colored-tiles-6-768x576.jpg\" class=\"skip-lazy\" alt=\"\" loading=\"eager\" data-lazy-srcset=\"https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-colored-tiles-6-768x576.jpg 768w,  https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-colored-tiles-6-300x225.jpg 300w,  https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-colored-tiles-6-600x450.jpg 600w\" data-lazy-sizes=\"(max-width: 768px) 100vw, 768px\" data-lazy-src=\"https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-colored-tiles-6-768x576.jpg?is-pending-load=1\" srcset=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAAKgAAAB+CAYAAACwLFqGAAAACXBIWXMAAA7EAAAOxAGVKw4bAAAAaUlEQVR42u3BAQ0AAADCoPdPbQ43oAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAACeDEtNAAGpFkl8AAAAAElFTkSuQmCC\" \/><\/div><\/a><\/div><a href=\"https:\/\/www.pinterest.com\/pin\/create\/button\/\" data-pin-do=\"buttonPin\" data-pin-hover=\"true\" data-pin-media=\"https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-colored-tiles-6-768x576.jpg\" data-pin-url=\"\" style=\"position: absolute; top: 10px; left:10px;\"> <\/a><\/div><div class=\"gt3pg-isotope-item loading\" ><div class=\"isotope_item-wrapper\"><a href=\"https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-colored-tiles-7-768x486.jpg\" class=\"gt3pg-lightbox\"  target=\"_blank\" data-elementor-open-lightbox=\"no\"><div class=\"img-wrapper\"><img decoding=\"async\" width=\"768\" height=\"486\" src=\"https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-colored-tiles-7-768x486.jpg\" class=\"skip-lazy\" alt=\"\" loading=\"eager\" data-lazy-srcset=\"https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-colored-tiles-7-768x486.jpg 768w,  https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-colored-tiles-7-300x190.jpg 300w,  https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-colored-tiles-7-600x380.jpg 600w\" data-lazy-sizes=\"(max-width: 768px) 100vw, 768px\" data-lazy-src=\"https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-colored-tiles-7-768x486.jpg?is-pending-load=1\" srcset=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAAFoAAAA4CAYAAAB9lO9TAAAACXBIWXMAAA7EAAAOxAGVKw4bAAAAKklEQVR42u3BMQEAAADCoPVPbQo\/oAAAAAAAAAAAAAAAAAAAAAAAAADgZ074AAGdwMPDAAAAAElFTkSuQmCC\" \/><\/div><\/a><\/div><a href=\"https:\/\/www.pinterest.com\/pin\/create\/button\/\" data-pin-do=\"buttonPin\" data-pin-hover=\"true\" data-pin-media=\"https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-colored-tiles-7-768x486.jpg\" data-pin-url=\"\" style=\"position: absolute; top: 10px; left:10px;\"> <\/a><\/div><div class=\"gt3pg-isotope-item loading\" ><div class=\"isotope_item-wrapper\"><a href=\"https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-colored-tiles-8-768x409.jpg\" class=\"gt3pg-lightbox\"  target=\"_blank\" data-elementor-open-lightbox=\"no\"><div class=\"img-wrapper\"><img decoding=\"async\" width=\"768\" height=\"409\" src=\"https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-colored-tiles-8-768x409.jpg\" class=\"skip-lazy\" alt=\"\" loading=\"eager\" data-lazy-srcset=\"https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-colored-tiles-8-768x409.jpg 768w,  https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-colored-tiles-8-300x160.jpg 300w,  https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-colored-tiles-8-600x320.jpg 600w\" data-lazy-sizes=\"(max-width: 768px) 100vw, 768px\" data-lazy-src=\"https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-colored-tiles-8-768x409.jpg?is-pending-load=1\" srcset=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAAJYAAABPCAYAAAAJMDwFAAAACXBIWXMAAA7EAAAOxAGVKw4bAAAARElEQVR42u3BAQEAAACAkP6v7ggKAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAoKoBuXcAAUcOF\/MAAAAASUVORK5CYII=\" \/><\/div><\/a><\/div><a href=\"https:\/\/www.pinterest.com\/pin\/create\/button\/\" data-pin-do=\"buttonPin\" data-pin-hover=\"true\" data-pin-media=\"https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-colored-tiles-8-768x409.jpg\" data-pin-url=\"\" style=\"position: absolute; top: 10px; left:10px;\"> <\/a><\/div><div class=\"gt3pg-isotope-item loading\" ><div class=\"isotope_item-wrapper\"><a href=\"https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-colored-tiles-9-768x432.jpg\" class=\"gt3pg-lightbox\"  target=\"_blank\" data-elementor-open-lightbox=\"no\"><div class=\"img-wrapper\"><img decoding=\"async\" width=\"768\" height=\"432\" src=\"https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-colored-tiles-9-768x432.jpg\" class=\"skip-lazy\" alt=\"\" loading=\"eager\" data-lazy-srcset=\"https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-colored-tiles-9-768x432.jpg 768w,  https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-colored-tiles-9-300x169.jpg 300w,  https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-colored-tiles-9-600x338.jpg 600w\" data-lazy-sizes=\"(max-width: 768px) 100vw, 768px\" data-lazy-src=\"https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-colored-tiles-9-768x432.jpg?is-pending-load=1\" srcset=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAAMAAAABrCAYAAAAhB40qAAAACXBIWXMAAA7EAAAOxAGVKw4bAAAAZklEQVR42u3BAQEAAACCIP+vbkhAAQAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAMCVAUF6AAF5yzVlAAAAAElFTkSuQmCC\" \/><\/div><\/a><\/div><a href=\"https:\/\/www.pinterest.com\/pin\/create\/button\/\" data-pin-do=\"buttonPin\" data-pin-hover=\"true\" data-pin-media=\"https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-colored-tiles-9-768x432.jpg\" data-pin-url=\"\" style=\"position: absolute; top: 10px; left:10px;\"> <\/a><\/div><div class=\"gt3pg-isotope-item loading\" ><div class=\"isotope_item-wrapper\"><a href=\"https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-colored-tiles-10-768x576.jpg\" class=\"gt3pg-lightbox\"  target=\"_blank\" data-elementor-open-lightbox=\"no\"><div class=\"img-wrapper\"><img decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-colored-tiles-10-768x576.jpg\" class=\"skip-lazy\" alt=\"\" loading=\"eager\" data-lazy-srcset=\"https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-colored-tiles-10-768x576.jpg 768w,  https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-colored-tiles-10-300x225.jpg 300w,  https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-colored-tiles-10-600x450.jpg 600w\" data-lazy-sizes=\"(max-width: 768px) 100vw, 768px\" data-lazy-src=\"https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-colored-tiles-10-768x576.jpg?is-pending-load=1\" srcset=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAAG0AAABRCAYAAADYQCiAAAAACXBIWXMAAA7EAAAOxAGVKw4bAAAAOUlEQVR42u3BMQEAAADCoPVPbQZ\/oAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAC4DYpFAAHYK0V1AAAAAElFTkSuQmCC\" \/><\/div><\/a><\/div><a href=\"https:\/\/www.pinterest.com\/pin\/create\/button\/\" data-pin-do=\"buttonPin\" data-pin-hover=\"true\" data-pin-media=\"https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-colored-tiles-10-768x576.jpg\" data-pin-url=\"\" style=\"position: absolute; top: 10px; left:10px;\"> <\/a><\/div><div class=\"gt3pg-isotope-item loading\" ><div class=\"isotope_item-wrapper\"><a href=\"https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-colored-tiles-11-768x516.jpg\" class=\"gt3pg-lightbox\"  target=\"_blank\" data-elementor-open-lightbox=\"no\"><div class=\"img-wrapper\"><img decoding=\"async\" width=\"768\" height=\"516\" src=\"https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-colored-tiles-11-768x516.jpg\" class=\"skip-lazy\" alt=\"\" loading=\"eager\" data-lazy-srcset=\"https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-colored-tiles-11-768x516.jpg 768w,  https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-colored-tiles-11-300x201.jpg 300w,  https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-colored-tiles-11-600x403.jpg 600w\" data-lazy-sizes=\"(max-width: 768px) 100vw, 768px\" data-lazy-src=\"https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-colored-tiles-11-768x516.jpg?is-pending-load=1\" srcset=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAAIUAAABZCAYAAAAQJudoAAAACXBIWXMAAA7EAAAOxAGVKw4bAAAARElEQVR42u3BAQ0AAADCoPdPbQ8HFAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAHBtuU0AAZ97QE0AAAAASUVORK5CYII=\" \/><\/div><\/a><\/div><a href=\"https:\/\/www.pinterest.com\/pin\/create\/button\/\" data-pin-do=\"buttonPin\" data-pin-hover=\"true\" data-pin-media=\"https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-colored-tiles-11-768x516.jpg\" data-pin-url=\"\" style=\"position: absolute; top: 10px; left:10px;\"> <\/a><\/div><div class=\"gt3pg-isotope-item loading\" ><div class=\"isotope_item-wrapper\"><a href=\"https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-colored-tiles-12-768x576.jpg\" class=\"gt3pg-lightbox\"  target=\"_blank\" data-elementor-open-lightbox=\"no\"><div class=\"img-wrapper\"><img decoding=\"async\" width=\"768\" height=\"576\" src=\"https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-colored-tiles-12-768x576.jpg\" class=\"skip-lazy\" alt=\"\" loading=\"eager\" data-lazy-srcset=\"https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-colored-tiles-12-768x576.jpg 768w,  https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-colored-tiles-12-300x225.jpg 300w,  https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-colored-tiles-12-600x450.jpg 600w\" data-lazy-sizes=\"(max-width: 768px) 100vw, 768px\" data-lazy-src=\"https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-colored-tiles-12-768x576.jpg?is-pending-load=1\" srcset=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAAKAAAAB4CAYAAAB1ovlvAAAACXBIWXMAAA7EAAAOxAGVKw4bAAAAYUlEQVR42u3BgQAAAADDoPlTH+ECVQEAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAAwDcshwAB\/hSSxAAAAABJRU5ErkJggg==\" \/><\/div><\/a><\/div><a href=\"https:\/\/www.pinterest.com\/pin\/create\/button\/\" data-pin-do=\"buttonPin\" data-pin-hover=\"true\" data-pin-media=\"https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-colored-tiles-12-768x576.jpg\" data-pin-url=\"\" style=\"position: absolute; top: 10px; left:10px;\"> <\/a><\/div>\t\t\t<\/div>\r\n\t\t\t<div class=\"gallery-preloader\"><svg width=\"50\" height=\"50\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 100 100\" preserveAspectRatio=\"xMidYMid\" class=\"lds-eclipse\"><path stroke=\"none\" d=\"M10 50A40 40 0 0 0 90 50A40 42 0 0 1 10 50\"><\/path><\/svg><\/div>\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t<script type=\"application\/json\" id=\"settings--uid-a1962ff3b47b5dfd\">{\"id\":1,\"uid\":\"uid-a1962ff3b47b5dfd\",\"grid_type\":\"square\",\"lazyLoad\":true,\"isotopeOptions\":{\"stagger\":0},\"lightbox\":{\"enable\":true,\"options\":{\"showTitle\":false,\"showCaption\":false,\"descriptionProperty\":\"caption\",\"allowDownload\":false,\"allowZoom\":true,\"socials\":true,\"deepLink\":false,\"stretchImages\":false,\"thumbnailIndicators\":true,\"startSlideshow\":false,\"slideshowInterval\":6000,\"instance\":3,\"customClass\":\"style-dark\",\"rightClick\":false,\"externalPosters\":false,\"ytWidth\":false,\"toggleControlsOnSlideClick\":false,\"closeOnSlideClick\":false,\"videoAutoplay\":false,\"animationType\":\"slide\",\"simpleStyle\":false,\"continuous\":true}},\"items\":[{\"href\":\"https:\\\/\\\/www.hackrea.net\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/Pastel-colored-tiles-1.jpg\",\"title\":\"Pastel-colored tiles-1\",\"caption\":\"\",\"description\":\"\",\"alt\":\"\",\"thumbnail\":\"https:\\\/\\\/www.hackrea.net\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/Pastel-colored-tiles-1-150x150.jpg\",\"is_video\":0,\"image_id\":5719534,\"width\":900,\"height\":646,\"item_class_list\":[],\"external_link\":\"\",\"local_index\":0},{\"href\":\"https:\\\/\\\/www.hackrea.net\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/Pastel-colored-tiles-2.jpg\",\"title\":\"Pastel-colored tiles-2\",\"caption\":\"\",\"description\":\"\",\"alt\":\"\",\"thumbnail\":\"https:\\\/\\\/www.hackrea.net\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/Pastel-colored-tiles-2-150x150.jpg\",\"is_video\":0,\"image_id\":5719535,\"width\":1492,\"height\":1002,\"item_class_list\":[],\"external_link\":\"\",\"local_index\":1},{\"href\":\"https:\\\/\\\/www.hackrea.net\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/Pastel-colored-tiles-3.jpg\",\"title\":\"Pastel-colored tiles-3\",\"caption\":\"\",\"description\":\"\",\"alt\":\"\",\"thumbnail\":\"https:\\\/\\\/www.hackrea.net\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/Pastel-colored-tiles-3-150x150.jpg\",\"is_video\":0,\"image_id\":5719536,\"width\":735,\"height\":600,\"item_class_list\":[],\"external_link\":\"\",\"local_index\":2},{\"href\":\"https:\\\/\\\/www.hackrea.net\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/Pastel-colored-tiles-4.jpg\",\"title\":\"Pastel-colored tiles-4\",\"caption\":\"\",\"description\":\"\",\"alt\":\"\",\"thumbnail\":\"https:\\\/\\\/www.hackrea.net\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/Pastel-colored-tiles-4-150x150.jpg\",\"is_video\":0,\"image_id\":5719537,\"width\":1334,\"height\":896,\"item_class_list\":[],\"external_link\":\"\",\"local_index\":3},{\"href\":\"https:\\\/\\\/www.hackrea.net\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/Pastel-colored-tiles-5.jpg\",\"title\":\"Pastel-colored tiles-5\",\"caption\":\"\",\"description\":\"\",\"alt\":\"\",\"thumbnail\":\"https:\\\/\\\/www.hackrea.net\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/Pastel-colored-tiles-5-150x150.jpg\",\"is_video\":0,\"image_id\":5719538,\"width\":1900,\"height\":1069,\"item_class_list\":[],\"external_link\":\"\",\"local_index\":4},{\"href\":\"https:\\\/\\\/www.hackrea.net\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/Pastel-colored-tiles-6.jpg\",\"title\":\"Pastel-colored tiles-6\",\"caption\":\"\",\"description\":\"\",\"alt\":\"\",\"thumbnail\":\"https:\\\/\\\/www.hackrea.net\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/Pastel-colored-tiles-6-150x150.jpg\",\"is_video\":0,\"image_id\":5719539,\"width\":1680,\"height\":1260,\"item_class_list\":[],\"external_link\":\"\",\"local_index\":5},{\"href\":\"https:\\\/\\\/www.hackrea.net\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/Pastel-colored-tiles-7.jpg\",\"title\":\"Pastel-colored tiles-7\",\"caption\":\"\",\"description\":\"\",\"alt\":\"\",\"thumbnail\":\"https:\\\/\\\/www.hackrea.net\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/Pastel-colored-tiles-7-150x150.jpg\",\"is_video\":0,\"image_id\":5719540,\"width\":900,\"height\":570,\"item_class_list\":[],\"external_link\":\"\",\"local_index\":6},{\"href\":\"https:\\\/\\\/www.hackrea.net\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/Pastel-colored-tiles-8.jpg\",\"title\":\"Pastel-colored tiles-8\",\"caption\":\"\",\"description\":\"\",\"alt\":\"\",\"thumbnail\":\"https:\\\/\\\/www.hackrea.net\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/Pastel-colored-tiles-8-150x150.jpg\",\"is_video\":0,\"image_id\":5719541,\"width\":1495,\"height\":797,\"item_class_list\":[],\"external_link\":\"\",\"local_index\":7},{\"href\":\"https:\\\/\\\/www.hackrea.net\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/Pastel-colored-tiles-9.jpg\",\"title\":\"Pastel-colored tiles-9\",\"caption\":\"\",\"description\":\"\",\"alt\":\"\",\"thumbnail\":\"https:\\\/\\\/www.hackrea.net\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/Pastel-colored-tiles-9-150x150.jpg\",\"is_video\":0,\"image_id\":5719542,\"width\":1920,\"height\":1080,\"item_class_list\":[],\"external_link\":\"\",\"local_index\":8},{\"href\":\"https:\\\/\\\/www.hackrea.net\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/Pastel-colored-tiles-10.jpg\",\"title\":\"Pastel-colored tiles-10\",\"caption\":\"\",\"description\":\"\",\"alt\":\"\",\"thumbnail\":\"https:\\\/\\\/www.hackrea.net\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/Pastel-colored-tiles-10-150x150.jpg\",\"is_video\":0,\"image_id\":5719543,\"width\":1093,\"height\":820,\"item_class_list\":[],\"external_link\":\"\",\"local_index\":9},{\"href\":\"https:\\\/\\\/www.hackrea.net\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/Pastel-colored-tiles-11.jpg\",\"title\":\"Pastel-colored tiles-11\",\"caption\":\"\",\"description\":\"\",\"alt\":\"\",\"thumbnail\":\"https:\\\/\\\/www.hackrea.net\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/Pastel-colored-tiles-11-150x150.jpg\",\"is_video\":0,\"image_id\":5719544,\"width\":1334,\"height\":896,\"item_class_list\":[],\"external_link\":\"\",\"local_index\":10},{\"href\":\"https:\\\/\\\/www.hackrea.net\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/Pastel-colored-tiles-12.jpg\",\"title\":\"Pastel-colored tiles-12\",\"caption\":\"\",\"description\":\"\",\"alt\":\"\",\"thumbnail\":\"https:\\\/\\\/www.hackrea.net\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/Pastel-colored-tiles-12-150x150.jpg\",\"is_video\":0,\"image_id\":5719545,\"width\":1600,\"height\":1200,\"item_class_list\":[],\"external_link\":\"\",\"local_index\":11}],\"modules\":[\"Lightbox\"]}<\/script><\/div>","protected":false},"excerpt":{"rendered":"<p>Le monde, plong\u00e9 dans la palette de couleurs de l&#8217;automne, prend une atmosph\u00e8re plus nostalgique. Les flammes chaudes qui dansent&#8230;<\/p>","protected":false},"author":14,"featured_media":5718978,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[633,1050],"tags":[3526,3787,3522,3528],"featured_image_urls":{"full":["https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-colored-tiles-in-modern-interiors-cover.jpg",1920,1496,false],"thumbnail":["https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-colored-tiles-in-modern-interiors-cover-150x150.jpg",150,150,true],"medium":["https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-colored-tiles-in-modern-interiors-cover-300x234.jpg",300,234,true],"medium_large":["https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-colored-tiles-in-modern-interiors-cover-768x598.jpg",768,598,true],"large":["https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-colored-tiles-in-modern-interiors-cover-1024x798.jpg",1024,798,true]},"post_excerpt_stackable":"<p>Le monde, plong\u00e9 dans la palette de couleurs de l&#8217;automne, prend une atmosph\u00e8re plus nostalgique. Les flammes chaudes qui dansent dans la chemin\u00e9e vous plongent dans les souvenirs du printemps et de l&#8217;\u00e9t\u00e9 associ\u00e9s aux pastels: la fra\u00eecheur des p\u00eaches, le parfum des fleurs, ou le go\u00fbt de la glace. Cette l\u00e9g\u00e8ret\u00e9 et ce charme des mois d&#8217;\u00e9t\u00e9 peuvent \u00eatre pr\u00e9serv\u00e9s plus longtemps en ajoutant du carrelage des nuances d\u00e9licates \u00e0 l&#8217;int\u00e9rieur, vous permettant de vivre une joie insouciante, quelle que soit la temp\u00e9rature \u00e0 l&#8217;ext\u00e9rieur de la fen\u00eatre. Les pastels \u00e9taient auparavant utilis\u00e9s principalement pour la chambre d\u2019enfants pour\u2026<\/p>","category_list":"<a href=\"https:\/\/www.hackrea.net\/fr\/stories\/category\/decoration\/maison\/revetement\/carrelage\/\" rel=\"category tag\">Carrelage<\/a>, <a href=\"https:\/\/www.hackrea.net\/fr\/stories\/category\/decoration\/maison\/revetement-de-sol\/\" rel=\"category tag\">Rev\u00eatement de sol<\/a>","author_info":{"name":"Hackrea Com","url":"https:\/\/www.hackrea.net\/fr\/author\/community\/"},"comments_num":"0 commentaire","featured_image_urls_v2":{"full":["https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-colored-tiles-in-modern-interiors-cover.jpg",1920,1496,false],"thumbnail":["https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-colored-tiles-in-modern-interiors-cover-150x150.jpg",150,150,true],"medium":["https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-colored-tiles-in-modern-interiors-cover-300x234.jpg",300,234,true],"medium_large":["https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-colored-tiles-in-modern-interiors-cover-768x598.jpg",768,598,true],"large":["https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-colored-tiles-in-modern-interiors-cover-1024x798.jpg",1024,798,true]},"post_excerpt_stackable_v2":"<p>Le monde, plong\u00e9 dans la palette de couleurs de l&#8217;automne, prend une atmosph\u00e8re plus nostalgique. Les flammes chaudes qui dansent dans la chemin\u00e9e vous plongent dans les souvenirs du printemps et de l&#8217;\u00e9t\u00e9 associ\u00e9s aux pastels: la fra\u00eecheur des p\u00eaches, le parfum des fleurs, ou le go\u00fbt de la glace. Cette l\u00e9g\u00e8ret\u00e9 et ce charme des mois d&#8217;\u00e9t\u00e9 peuvent \u00eatre pr\u00e9serv\u00e9s plus longtemps en ajoutant du carrelage des nuances d\u00e9licates \u00e0 l&#8217;int\u00e9rieur, vous permettant de vivre une joie insouciante, quelle que soit la temp\u00e9rature \u00e0 l&#8217;ext\u00e9rieur de la fen\u00eatre. Les pastels \u00e9taient auparavant utilis\u00e9s principalement pour la chambre d\u2019enfants pour\u2026<\/p>","category_list_v2":"<a href=\"https:\/\/www.hackrea.net\/fr\/stories\/category\/decoration\/maison\/revetement\/carrelage\/\" rel=\"category tag\">Carrelage<\/a>, <a href=\"https:\/\/www.hackrea.net\/fr\/stories\/category\/decoration\/maison\/revetement-de-sol\/\" rel=\"category tag\">Rev\u00eatement de sol<\/a>","author_info_v2":{"name":"Hackrea Com","url":"https:\/\/www.hackrea.net\/fr\/author\/community\/"},"comments_num_v2":"0 commentaire","yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Carrelage pastel: caract\u00e9ristiques d&#039;utilisation \u00e0 l&#039;int\u00e9rieur - Hackrea<\/title>\n<meta name=\"description\" content=\"Le carrelage de couleur pastel augmentent l&#039;espace et d\u00e9tende, il n&#039;est donc pas surprenant que parmi les tendances dominantes, ces teintes douces aient re\u00e7u le plus grand groupe de supporters.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.hackrea.net\/fr\/stories\/carrelage-pastel\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Carrelage pastel: caract\u00e9ristiques d&#039;utilisation \u00e0 l&#039;int\u00e9rieur - Hackrea\" \/>\n<meta property=\"og:description\" content=\"Le carrelage de couleur pastel augmentent l&#039;espace et d\u00e9tende, il n&#039;est donc pas surprenant que parmi les tendances dominantes, ces teintes douces aient re\u00e7u le plus grand groupe de supporters.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.hackrea.net\/fr\/stories\/carrelage-pastel\/\" \/>\n<meta property=\"og:site_name\" content=\"Hackrea\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-09T05:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-03-09T05:26:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-colored-tiles-in-modern-interiors-cover.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1496\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Hackrea Com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Hackrea Com\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.hackrea.net\/fr\/stories\/carrelage-pastel\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.hackrea.net\/fr\/stories\/carrelage-pastel\/\"},\"author\":{\"name\":\"Hackrea Com\",\"@id\":\"https:\/\/www.hackrea.net\/fr\/#\/schema\/person\/608e57bf7211a7a99947cfc407725fb4\"},\"headline\":\"Carrelage pastel: caract\u00e9ristiques d&#8217;utilisation \u00e0 l&#8217;int\u00e9rieur\",\"datePublished\":\"2021-03-09T05:00:00+00:00\",\"dateModified\":\"2021-03-09T05:26:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.hackrea.net\/fr\/stories\/carrelage-pastel\/\"},\"wordCount\":1465,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.hackrea.net\/fr\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.hackrea.net\/fr\/stories\/carrelage-pastel\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-colored-tiles-in-modern-interiors-cover.jpg\",\"keywords\":[\"carrelage pastel\",\"couleur carrelage\",\"mur de couleur pastel\",\"rev\u00eatement de sol de couleur pastel\"],\"articleSection\":[\"Carrelage\",\"Rev\u00eatement de sol\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.hackrea.net\/fr\/stories\/carrelage-pastel\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.hackrea.net\/fr\/stories\/carrelage-pastel\/\",\"url\":\"https:\/\/www.hackrea.net\/fr\/stories\/carrelage-pastel\/\",\"name\":\"Carrelage pastel: caract\u00e9ristiques d'utilisation \u00e0 l'int\u00e9rieur - Hackrea\",\"isPartOf\":{\"@id\":\"https:\/\/www.hackrea.net\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.hackrea.net\/fr\/stories\/carrelage-pastel\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.hackrea.net\/fr\/stories\/carrelage-pastel\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-colored-tiles-in-modern-interiors-cover.jpg\",\"datePublished\":\"2021-03-09T05:00:00+00:00\",\"dateModified\":\"2021-03-09T05:26:57+00:00\",\"description\":\"Le carrelage de couleur pastel augmentent l'espace et d\u00e9tende, il n'est donc pas surprenant que parmi les tendances dominantes, ces teintes douces aient re\u00e7u le plus grand groupe de supporters.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.hackrea.net\/fr\/stories\/carrelage-pastel\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.hackrea.net\/fr\/stories\/carrelage-pastel\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.hackrea.net\/fr\/stories\/carrelage-pastel\/#primaryimage\",\"url\":\"https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-colored-tiles-in-modern-interiors-cover.jpg\",\"contentUrl\":\"https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-colored-tiles-in-modern-interiors-cover.jpg\",\"width\":1920,\"height\":1496},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.hackrea.net\/fr\/stories\/carrelage-pastel\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Hackrea\",\"item\":\"https:\/\/www.hackrea.net\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Carrelage pastel: caract\u00e9ristiques d&#8217;utilisation \u00e0 l&#8217;int\u00e9rieur\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.hackrea.net\/fr\/#website\",\"url\":\"https:\/\/www.hackrea.net\/fr\/\",\"name\":\"Hackrea\",\"description\":\"For and by people that create\",\"publisher\":{\"@id\":\"https:\/\/www.hackrea.net\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.hackrea.net\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.hackrea.net\/fr\/#organization\",\"name\":\"Hackrea\",\"url\":\"https:\/\/www.hackrea.net\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.hackrea.net\/fr\/#\/schema\/logo\/image\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Hackrea\"},\"image\":{\"@id\":\"https:\/\/www.hackrea.net\/fr\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.hackrea.net\/fr\/#\/schema\/person\/608e57bf7211a7a99947cfc407725fb4\",\"name\":\"Hackrea Com\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.hackrea.net\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/4ff4700d47f912c27f14f2bd5094b02d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/4ff4700d47f912c27f14f2bd5094b02d?s=96&d=mm&r=g\",\"caption\":\"Hackrea Com\"},\"url\":\"https:\/\/www.hackrea.net\/fr\/author\/community\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Carrelage pastel: caract\u00e9ristiques d'utilisation \u00e0 l'int\u00e9rieur - Hackrea","description":"Le carrelage de couleur pastel augmentent l'espace et d\u00e9tende, il n'est donc pas surprenant que parmi les tendances dominantes, ces teintes douces aient re\u00e7u le plus grand groupe de supporters.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.hackrea.net\/fr\/stories\/carrelage-pastel\/","og_locale":"fr_FR","og_type":"article","og_title":"Carrelage pastel: caract\u00e9ristiques d'utilisation \u00e0 l'int\u00e9rieur - Hackrea","og_description":"Le carrelage de couleur pastel augmentent l'espace et d\u00e9tende, il n'est donc pas surprenant que parmi les tendances dominantes, ces teintes douces aient re\u00e7u le plus grand groupe de supporters.","og_url":"https:\/\/www.hackrea.net\/fr\/stories\/carrelage-pastel\/","og_site_name":"Hackrea","article_published_time":"2021-03-09T05:00:00+00:00","article_modified_time":"2021-03-09T05:26:57+00:00","og_image":[{"width":1920,"height":1496,"url":"https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-colored-tiles-in-modern-interiors-cover.jpg","type":"image\/jpeg"}],"author":"Hackrea Com","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Hackrea Com","Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.hackrea.net\/fr\/stories\/carrelage-pastel\/#article","isPartOf":{"@id":"https:\/\/www.hackrea.net\/fr\/stories\/carrelage-pastel\/"},"author":{"name":"Hackrea Com","@id":"https:\/\/www.hackrea.net\/fr\/#\/schema\/person\/608e57bf7211a7a99947cfc407725fb4"},"headline":"Carrelage pastel: caract\u00e9ristiques d&#8217;utilisation \u00e0 l&#8217;int\u00e9rieur","datePublished":"2021-03-09T05:00:00+00:00","dateModified":"2021-03-09T05:26:57+00:00","mainEntityOfPage":{"@id":"https:\/\/www.hackrea.net\/fr\/stories\/carrelage-pastel\/"},"wordCount":1465,"commentCount":0,"publisher":{"@id":"https:\/\/www.hackrea.net\/fr\/#organization"},"image":{"@id":"https:\/\/www.hackrea.net\/fr\/stories\/carrelage-pastel\/#primaryimage"},"thumbnailUrl":"https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-colored-tiles-in-modern-interiors-cover.jpg","keywords":["carrelage pastel","couleur carrelage","mur de couleur pastel","rev\u00eatement de sol de couleur pastel"],"articleSection":["Carrelage","Rev\u00eatement de sol"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.hackrea.net\/fr\/stories\/carrelage-pastel\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.hackrea.net\/fr\/stories\/carrelage-pastel\/","url":"https:\/\/www.hackrea.net\/fr\/stories\/carrelage-pastel\/","name":"Carrelage pastel: caract\u00e9ristiques d'utilisation \u00e0 l'int\u00e9rieur - Hackrea","isPartOf":{"@id":"https:\/\/www.hackrea.net\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.hackrea.net\/fr\/stories\/carrelage-pastel\/#primaryimage"},"image":{"@id":"https:\/\/www.hackrea.net\/fr\/stories\/carrelage-pastel\/#primaryimage"},"thumbnailUrl":"https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-colored-tiles-in-modern-interiors-cover.jpg","datePublished":"2021-03-09T05:00:00+00:00","dateModified":"2021-03-09T05:26:57+00:00","description":"Le carrelage de couleur pastel augmentent l'espace et d\u00e9tende, il n'est donc pas surprenant que parmi les tendances dominantes, ces teintes douces aient re\u00e7u le plus grand groupe de supporters.","breadcrumb":{"@id":"https:\/\/www.hackrea.net\/fr\/stories\/carrelage-pastel\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.hackrea.net\/fr\/stories\/carrelage-pastel\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.hackrea.net\/fr\/stories\/carrelage-pastel\/#primaryimage","url":"https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-colored-tiles-in-modern-interiors-cover.jpg","contentUrl":"https:\/\/www.hackrea.net\/wp-content\/uploads\/2021\/01\/Pastel-colored-tiles-in-modern-interiors-cover.jpg","width":1920,"height":1496},{"@type":"BreadcrumbList","@id":"https:\/\/www.hackrea.net\/fr\/stories\/carrelage-pastel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Hackrea","item":"https:\/\/www.hackrea.net\/fr\/"},{"@type":"ListItem","position":2,"name":"Carrelage pastel: caract\u00e9ristiques d&#8217;utilisation \u00e0 l&#8217;int\u00e9rieur"}]},{"@type":"WebSite","@id":"https:\/\/www.hackrea.net\/fr\/#website","url":"https:\/\/www.hackrea.net\/fr\/","name":"Hackrea","description":"For and by people that create","publisher":{"@id":"https:\/\/www.hackrea.net\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.hackrea.net\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.hackrea.net\/fr\/#organization","name":"Hackrea","url":"https:\/\/www.hackrea.net\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.hackrea.net\/fr\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Hackrea"},"image":{"@id":"https:\/\/www.hackrea.net\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.hackrea.net\/fr\/#\/schema\/person\/608e57bf7211a7a99947cfc407725fb4","name":"Hackrea Com","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.hackrea.net\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/4ff4700d47f912c27f14f2bd5094b02d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4ff4700d47f912c27f14f2bd5094b02d?s=96&d=mm&r=g","caption":"Hackrea Com"},"url":"https:\/\/www.hackrea.net\/fr\/author\/community\/"}]}},"_links":{"self":[{"href":"https:\/\/www.hackrea.net\/fr\/wp-json\/wp\/v2\/posts\/5721209"}],"collection":[{"href":"https:\/\/www.hackrea.net\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hackrea.net\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hackrea.net\/fr\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hackrea.net\/fr\/wp-json\/wp\/v2\/comments?post=5721209"}],"version-history":[{"count":0,"href":"https:\/\/www.hackrea.net\/fr\/wp-json\/wp\/v2\/posts\/5721209\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hackrea.net\/fr\/wp-json\/wp\/v2\/media\/5718978"}],"wp:attachment":[{"href":"https:\/\/www.hackrea.net\/fr\/wp-json\/wp\/v2\/media?parent=5721209"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hackrea.net\/fr\/wp-json\/wp\/v2\/categories?post=5721209"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hackrea.net\/fr\/wp-json\/wp\/v2\/tags?post=5721209"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}